{"id":27,"date":"2026-08-02T10:38:11","date_gmt":"2026-08-02T10:38:11","guid":{"rendered":"https:\/\/synapsecircle.com\/campuscircle\/customer-cabinet\/"},"modified":"2026-08-02T10:38:11","modified_gmt":"2026-08-02T10:38:11","slug":"customer-cabinet","status":"publish","type":"page","link":"https:\/\/synapsecircle.com\/campuscircle\/customer-cabinet\/","title":{"rendered":"Customer Cabinet"},"content":{"rendered":"<div class=\"latepoint-w\">\n\t<div class=\"os-form-w latepoint-login-form-w\" data-redirect-url=\"https:\/\/synapsecircle.com\/campuscircle\/customer-cabinet\" data-success-action=\"redirect\">\n                    <form action=\"\" class=\"latepoint-form\">\n                <div class=\"latepoint-customer-otp-input-container\"><\/div>\n                <div class=\"latepoint-customer-auth-options-wrapper hide-when-entering-otp\">\n                    <div class=\"latepoint-customer-box-title\">Sign in to your account<\/div>\n                    <div class=\"os-step-existing-customer-login-w\">\t\t\t<div class=\"os-customer-login-w os-customer-wrapped-box os-unwrapped\">\n\t\t\t\t\t\t\t\t<div data-login-method=\"email\" class=\"customer-login-method-wrapper \"><div class =\"os-form-group os-form-textfield-group os-form-group-transparent\" ><label for=\"auth_email\">Your Email Address<\/label><input  type=\"text\" placeholder=\"Your Email Address\" name=\"auth[email]\" value=\"\" autocomplete=\"email\" id=\"auth_email\" class=\"os-form-control\" \/><\/div><\/div>\t\t\t\t\t\t\t\t<div class=\"os-customer-login-password-fields-w\" >\n\t\t\t\t\t<div class=\"os-form-group os-form-textfield-group os-form-group-transparent\" ><label for=\"auth_password\">Your Password<\/label><input type=\"password\" placeholder=\"Your Password\" name=\"auth[password]\" value=\"\" class=\"required os-form-control\" autocomplete=\"current-password\" id=\"auth_password\" \/><\/div>\t\t\t\t\t<a href=\"#\" class=\"latepoint-btn latepoint-btn-primary latepoint-btn-link step-forgot-password-btn\"\n\t\t\t\t\t   data-os-action=\"customer_cabinet__request_password_reset_token\"\n\t\t\t\t\t   data-os-output-target=\".os-password-reset-form-holder\"\n\t\t\t\t\t   data-os-after-call=\"latepoint_reset_password_from_booking_init\"\n\t\t\t\t\t   data-os-params=\"from_booking=1\"><span>Forgot?<\/span><\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"os-customer-login-buttons\">\n\t\t\t\t\t<input type=\"hidden\" name=\"auth[via]\" value=\"password\" id=\"auth_via\" \/>\t\t\t\t\t<a data-otp-request-route=\"auth__request_otp\"\n\t\t\t\t\t   data-password-login-route=\"auth__login_customer\" href=\"#\"\n\t\t\t\t\t   class=\"latepoint-btn latepoint-btn-primary step-login-existing-customer-btn latepoint-btn-block\"><span>Continue<\/span><\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<input type=\"hidden\" name=\"auth[contact_type]\" value=\"email\" id=\"auth_contact_type\" \/><input type=\"hidden\" name=\"auth[delivery_method]\" value=\"email\" id=\"auth_delivery_method\" \/><input type=\"hidden\" name=\"auth[action]\" value=\"register\" id=\"auth_action\" \/><input type=\"hidden\" id=\"auth[nonce]\" name=\"auth[nonce]\" value=\"abf1f71983\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/campuscircle\/wp-json\/wp\/v2\/pages\/27\" \/><\/div><div class=\"os-password-reset-form-holder\"><\/div>                                    <\/div>\n            <\/form>\n            \t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/synapsecircle.com\/campuscircle\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}